{"id":3528,"date":"2016-07-19T07:30:51","date_gmt":"2016-07-19T05:30:51","guid":{"rendered":"http:\/\/www.superhumanoid.info\/superblog\/?p=3528"},"modified":"2020-05-05T07:01:38","modified_gmt":"2020-05-05T05:01:38","slug":"anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main","status":"publish","type":"post","link":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/","title":{"rendered":"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main)"},"content":{"rendered":"<p class=\"p1\"><em><span class=\"s1\">Auch dieses Jahr findet wieder das\u00a0DGPE-Jahressymposium mit\u00a0hochkar\u00e4tigen Rednern\u00a0statt.\u00a0Eine Vielzahl<span class=\"s1\">\u00a0Vortragender an einem Tag, kompakt und mit vielen Facetten rund um die Paleo-Ern\u00e4hrung und den Paleo-Lebensstil. Au\u00dferdem gibt es einen<\/span><span class=\"s1\">\u00a0Pal\u00e4o-Science Slam, dieser bietet DGPE-Mitgliedern die M\u00f6glichkeit, ihre Forschungs- oder Praxis-Projekte zur Paleo-Ern\u00e4hrung und dem Paleo-Lebensstil auf die Symposiums-B\u00fchne zu bringen.\u00a0<\/span><span class=\"s1\">Im Anschluss an das Symposium findet die <\/span><span class=\"s2\">Mitglieder-Versammlung der DGPE<\/span><span class=\"s1\"> statt.<\/span><\/span><\/em><\/p>\n<p class=\"p1\"><strong><span class=\"s1\"><a href=\"http:\/\/www.superhumanoid.info\/superblog\/2013\/10\/06\/erste-impressionen-vom-1-palao-symposium-der-dgpe-in-schweinfurt\/\">Impressionen vom\u00a01. Symposium gibt es hier<\/a>, vom <a href=\"http:\/\/www.superhumanoid.info\/superblog\/2014\/11\/09\/paleo-symposium-der-dgpe-impressionen-aus-schweinfurt\/\">2. Symposium hier<\/a>\u00a0und\u00a0vom <a href=\"http:\/\/www.superhumanoid.info\/superblog\/2015\/08\/09\/impressionen-vom-3-symposium-der-dgpe-e-v-2015-in-berlin\/\">3. Symposium hier<\/a>. <\/span><\/strong><span class=\"s1\">\ud83d\ude42<\/span><\/p>\n<h2 class=\"p1\">Ort und Zeit<\/h2>\n<ul>\n<li class=\"p1\"><span class=\"s1\"><b>Goethe-Universit\u00e4t Frankfurt, Unicampus Riedberg, Biozentrum<\/b><\/span><\/li>\n<li class=\"p1\"><span class=\"s1\"><b>Beginn: Samstag, 01.10.2016 um 08:30<\/b><\/span><\/li>\n<li class=\"p1\"><span class=\"s1\"><b>Ende: Samstag, 01.10.2016 um 20:00<\/b><\/span><\/li>\n<\/ul>\n<h2 class=\"p3\"><span class=\"s1\"><b>Programm<\/b><\/span><\/h2>\n<h3 class=\"p4\"><span class=\"s1\"><b>Schwerpunktthema 1: Fleisch &#8211; Nutzen, Risiken, Ethik<\/b><\/span><\/h3>\n<ul>\n<li class=\"p1\"><span class=\"s1\"><b>PD Dr. Ottmar Kullmer:<\/b> Pal\u00e4o-Cuisine &#8211; Erfolgsrezept auf dem Weg zum <i>Homo sapiens<\/i><\/span><\/li>\n<li class=\"p1\"><span class=\"s1\"><b>Dr. Jochen Hamatschek:<\/b> Die Ethik des Tiere t\u00f6tens &#8211; Sind Veganer die besseren Menschen?<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\"><b>Dr. Anita Idel:<\/b> Die Kuh ist kein Klimakiller &#8211; Zur Notwendigkeit nachhaltiger Beweidung f\u00fcr Weltern\u00e4hrung, Bodenfruchtbarkeit und Klima<\/span><\/li>\n<\/ul>\n<h3 class=\"p4\"><span class=\"s1\"><b>Schwerpunktthema 2: Pal\u00e4o-Ern\u00e4hrung in der Praxis<\/b><\/span><\/h3>\n<ul>\n<li class=\"p1\"><span class=\"s1\"><b>Andreas Schuster:<\/b> Eine Pal\u00e4o-Wanderung auf Sardinien &#8211; Neuronale und metabole Biorhythmen sanieren mit Ern\u00e4hrung und Bewegung<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\"><b>Bernd Schelker:<\/b> Fastende Tiere &#8211; Auswirkungen der Nahrungsrestriktion auf die Lebensspanne von Tier und Mensch<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\"><b>Dirk Lemke:<\/b> Kohlenhydrate in der Pal\u00e4o-Ern\u00e4hrung, Pathomechanismen der Hyperinsulin\u00e4mie<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\"><b>Prof. Dr. Ulrike K\u00e4mmerer:<\/b> Warum Hirn und Darm Ketone brauchen<\/span><\/li>\n<\/ul>\n<p class=\"p1\"><strong>Zur Ameldung geht es hier.<\/strong><\/p>\n<p class=\"p1\">\n","protected":false},"excerpt":{"rendered":"<p>Auch dieses Jahr findet wieder das\u00a0DGPE-Jahressymposium mit\u00a0hochkar\u00e4tigen Rednern\u00a0statt.\u00a0Eine Vielzahl\u00a0Vortragender an einem Tag, kompakt und mit vielen Facetten rund um die Paleo-Ern\u00e4hrung und den Paleo-Lebensstil. Au\u00dferdem gibt es einen\u00a0Pal\u00e4o-Science Slam, dieser&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Jetzt anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main).\r\n\r\nImpressionen vom 1. Symposium, vom 2. Symposium und vom 3. Symposium gibt es verlinkt im Artikel. :-)\r\n\r\nInfo: Auch dieses Jahr findet wieder das DGPE-Jahressymposium mit hochkar\u00e4tigen Rednern statt. 11 Vortragende an einem Tag, kompakt und mit vielen Facetten rund um die Paleo-Ern\u00e4hrung und den Paleo-Lebensstil. Au\u00dferdem gibt es einen Pal\u00e4o-Science Slam, dieser bietet DGPE-Mitgliedern die M\u00f6glichkeit, ihre Forschungs- oder Praxis-Projekte zur Paleo-Ern\u00e4hrung und dem Paleo-Lebensstil auf die Symposiums-B\u00fchne zu bringen. Im Anschluss an das Symposium findet die Mitglieder-Versammlung der DGPE statt.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[10,9,8,7],"tags":[1520,1184,1519,25,3,441,4,442],"class_list":["post-3528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dgpe","category-palao","category-paleo-2","category-symposium-2","tag-anmeldung","tag-dgpe","tag-jahressymposium","tag-palaeo","tag-paleo","tag-paleo-symposium","tag-symposium","tag-vortraege","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main) - superhumanoid.info blog<\/title>\n<meta name=\"description\" content=\"DGPE-Pal\u00e4o-Jahressymposium mit 11 hochkar\u00e4tigen Rednern an einem Tag, kompakt und mit vielen Facetten rund um die Paleo-Ern\u00e4hrung und den Paleo-Lebensstil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main)\" \/>\n<meta property=\"og:description\" content=\"Auch dieses Jahr findet wieder das DGPE-Jahressymposium mit hochkar\u00e4tigen Rednern statt. 11 Vortragende an einem Tag, kompakt und mit vielen Facetten rund um die Paleo-Ern\u00e4hrung und den Paleo-Lebensstil. Au\u00dferdem gibt es einen Pal\u00e4o-Science Slam, dieser bietet DGPE-Mitgliedern die M\u00f6glichkeit, ihre Forschungs- oder Praxis-Projekte zur Paleo-Ern\u00e4hrung und dem Paleo-Lebensstil auf die Symposiums-B\u00fchne zu bringen. Im Anschluss an das Symposium findet die Mitglieder-Versammlung der DGPE statt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/\" \/>\n<meta property=\"og:site_name\" content=\"superhumanoid.info blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/superhumanoid.info\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pawel.konefal\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-19T05:30:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-05T05:01:38+00:00\" \/>\n<meta name=\"author\" content=\"Pawel\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pawel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/\"},\"author\":{\"name\":\"Pawel\",\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/#\\\/schema\\\/person\\\/26af13acaaa4eda46bfea79065a73fa3\"},\"headline\":\"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main)\",\"datePublished\":\"2016-07-19T05:30:51+00:00\",\"dateModified\":\"2020-05-05T05:01:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/\"},\"wordCount\":234,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/superhumanoid.info\\\/superblog\\\/wp-content\\\/uploads\\\/4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main.jpg?fit=1024%2C512&ssl=1\",\"keywords\":[\"Anmeldung\",\"DGPE\",\"Jahressymposium\",\"Pal\u00e4o\",\"Paleo\",\"Paleo Symposium\",\"Symposium\",\"Vortr\u00e4ge\"],\"articleSection\":[\"DGPE\",\"Pal\u00e4o\",\"Paleo\",\"Symposium\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/\",\"url\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/\",\"name\":\"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main) - superhumanoid.info blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/superhumanoid.info\\\/superblog\\\/wp-content\\\/uploads\\\/4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main.jpg?fit=1024%2C512&ssl=1\",\"datePublished\":\"2016-07-19T05:30:51+00:00\",\"dateModified\":\"2020-05-05T05:01:38+00:00\",\"description\":\"DGPE-Pal\u00e4o-Jahressymposium mit 11 hochkar\u00e4tigen Rednern an einem Tag, kompakt und mit vielen Facetten rund um die Paleo-Ern\u00e4hrung und den Paleo-Lebensstil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/superhumanoid.info\\\/superblog\\\/wp-content\\\/uploads\\\/4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main.jpg?fit=1024%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/superhumanoid.info\\\/superblog\\\/wp-content\\\/uploads\\\/4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main.jpg?fit=1024%2C512&ssl=1\",\"width\":1024,\"height\":512,\"caption\":\"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/2016\\\/07\\\/19\\\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/#website\",\"url\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/\",\"name\":\"superhumanoid.info blog\",\"description\":\"Evolution\u00e4re Gesundheit mit Paleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/#organization\",\"name\":\"superhumanoid.info blog\",\"url\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/superhumanoid.info\\\/superblog\\\/wp-content\\\/uploads\\\/cropped-superhumanoid-info-logo-small.png?fit=260%2C60&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/superhumanoid.info\\\/superblog\\\/wp-content\\\/uploads\\\/cropped-superhumanoid-info-logo-small.png?fit=260%2C60&ssl=1\",\"width\":260,\"height\":60,\"caption\":\"superhumanoid.info blog\"},\"image\":{\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/superhumanoid.info\",\"https:\\\/\\\/x.com\\\/super_humanoid\",\"http:\\\/\\\/www.instagram.com\\\/superhumanoid.info\",\"http:\\\/\\\/pinterest.com\\\/super_humanoid\",\"http:\\\/\\\/www.youtube.com\\\/SuperhumanoidInfo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/#\\\/schema\\\/person\\\/26af13acaaa4eda46bfea79065a73fa3\",\"name\":\"Pawel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/www.superhumanoid.info\\\/superblog\\\/wp-content\\\/uploads\\\/Pawel_avatar_1404578456-96x96.jpg\",\"url\":\"http:\\\/\\\/www.superhumanoid.info\\\/superblog\\\/wp-content\\\/uploads\\\/Pawel_avatar_1404578456-96x96.jpg\",\"contentUrl\":\"http:\\\/\\\/www.superhumanoid.info\\\/superblog\\\/wp-content\\\/uploads\\\/Pawel_avatar_1404578456-96x96.jpg\",\"caption\":\"Pawel\"},\"description\":\"Pawel M. Konefal (geb. 22.02.1981 in Oberschlesien) ist freier Autor und Blogger und auch ein stetiger Selbst-Verbesserer. Er hat 80 kg in 2 Jahren abgenommen und sein K\u00f6rpergewicht halbiert. Er wei\u00df wie es ist stark \u00fcbergewichtig zu sein und ist voller Begeisterung mit den Themen Evolution\u00e4rer Gesundheit, Ern\u00e4hrung, Bewegung, Gehirnfitness und effektiver Selbstverbesserung besch\u00e4ftigt. Au\u00dferdem liebt er Kochen mit einfachen, nat\u00fcrlichen und unverarbeiteten Nahrungsmitteln. Er betreibt gerne Sport in Form von HIIT (Hoch Intensive Interval Training), Freeletics und ist begeisterter Leser. Er ern\u00e4hrt sich gem\u00e4\u00df der Paleo-Di\u00e4t bzw. Pal\u00e4o-Ern\u00e4hrung oder auch Steinzeit-Di\u00e4t und unterst\u00fctzt eine gesunde Lebensweise. Er hat den Anspruch seine Erfahrungen zu nutzen um anderen zu helfen.\",\"sameAs\":[\"http:\\\/\\\/www.superhumanoid.info\",\"https:\\\/\\\/www.facebook.com\\\/pawel.konefal\",\"https:\\\/\\\/instagram.com\\\/superhumanoid.info\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/super_humanoid\\\/\",\"https:\\\/\\\/x.com\\\/pawel_konefal\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/SuperhumanoidInfo\"],\"url\":\"https:\\\/\\\/superhumanoid.info\\\/superblog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main) - superhumanoid.info blog","description":"DGPE-Pal\u00e4o-Jahressymposium mit 11 hochkar\u00e4tigen Rednern an einem Tag, kompakt und mit vielen Facetten rund um die Paleo-Ern\u00e4hrung und den Paleo-Lebensstil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/","og_locale":"de_DE","og_type":"article","og_title":"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main)","og_description":"Auch dieses Jahr findet wieder das DGPE-Jahressymposium mit hochkar\u00e4tigen Rednern statt. 11 Vortragende an einem Tag, kompakt und mit vielen Facetten rund um die Paleo-Ern\u00e4hrung und den Paleo-Lebensstil. Au\u00dferdem gibt es einen Pal\u00e4o-Science Slam, dieser bietet DGPE-Mitgliedern die M\u00f6glichkeit, ihre Forschungs- oder Praxis-Projekte zur Paleo-Ern\u00e4hrung und dem Paleo-Lebensstil auf die Symposiums-B\u00fchne zu bringen. Im Anschluss an das Symposium findet die Mitglieder-Versammlung der DGPE statt.","og_url":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/","og_site_name":"superhumanoid.info blog","article_publisher":"https:\/\/www.facebook.com\/superhumanoid.info","article_author":"https:\/\/www.facebook.com\/pawel.konefal","article_published_time":"2016-07-19T05:30:51+00:00","article_modified_time":"2020-05-05T05:01:38+00:00","author":"Pawel","twitter_misc":{"Verfasst von":"Pawel","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/#article","isPartOf":{"@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/"},"author":{"name":"Pawel","@id":"https:\/\/superhumanoid.info\/superblog\/#\/schema\/person\/26af13acaaa4eda46bfea79065a73fa3"},"headline":"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main)","datePublished":"2016-07-19T05:30:51+00:00","dateModified":"2020-05-05T05:01:38+00:00","mainEntityOfPage":{"@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/"},"wordCount":234,"commentCount":0,"publisher":{"@id":"https:\/\/superhumanoid.info\/superblog\/#organization"},"image":{"@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/superhumanoid.info\/superblog\/wp-content\/uploads\/4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main.jpg?fit=1024%2C512&ssl=1","keywords":["Anmeldung","DGPE","Jahressymposium","Pal\u00e4o","Paleo","Paleo Symposium","Symposium","Vortr\u00e4ge"],"articleSection":["DGPE","Pal\u00e4o","Paleo","Symposium"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/","url":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/","name":"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main) - superhumanoid.info blog","isPartOf":{"@id":"https:\/\/superhumanoid.info\/superblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/#primaryimage"},"image":{"@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/superhumanoid.info\/superblog\/wp-content\/uploads\/4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main.jpg?fit=1024%2C512&ssl=1","datePublished":"2016-07-19T05:30:51+00:00","dateModified":"2020-05-05T05:01:38+00:00","description":"DGPE-Pal\u00e4o-Jahressymposium mit 11 hochkar\u00e4tigen Rednern an einem Tag, kompakt und mit vielen Facetten rund um die Paleo-Ern\u00e4hrung und den Paleo-Lebensstil.","breadcrumb":{"@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/#primaryimage","url":"https:\/\/i0.wp.com\/superhumanoid.info\/superblog\/wp-content\/uploads\/4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main.jpg?fit=1024%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/superhumanoid.info\/superblog\/wp-content\/uploads\/4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main.jpg?fit=1024%2C512&ssl=1","width":1024,"height":512,"caption":"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main)"},{"@type":"BreadcrumbList","@id":"https:\/\/superhumanoid.info\/superblog\/2016\/07\/19\/anmelden-zum-4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/superhumanoid.info\/superblog\/"},{"@type":"ListItem","position":2,"name":"Anmelden zum 4. Jahres-Symposium der DGPE (01.10.2016 in Frankfurt am Main)"}]},{"@type":"WebSite","@id":"https:\/\/superhumanoid.info\/superblog\/#website","url":"https:\/\/superhumanoid.info\/superblog\/","name":"superhumanoid.info blog","description":"Evolution\u00e4re Gesundheit mit Paleo","publisher":{"@id":"https:\/\/superhumanoid.info\/superblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/superhumanoid.info\/superblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/superhumanoid.info\/superblog\/#organization","name":"superhumanoid.info blog","url":"https:\/\/superhumanoid.info\/superblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/superhumanoid.info\/superblog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/superhumanoid.info\/superblog\/wp-content\/uploads\/cropped-superhumanoid-info-logo-small.png?fit=260%2C60&ssl=1","contentUrl":"https:\/\/i0.wp.com\/superhumanoid.info\/superblog\/wp-content\/uploads\/cropped-superhumanoid-info-logo-small.png?fit=260%2C60&ssl=1","width":260,"height":60,"caption":"superhumanoid.info blog"},"image":{"@id":"https:\/\/superhumanoid.info\/superblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/superhumanoid.info","https:\/\/x.com\/super_humanoid","http:\/\/www.instagram.com\/superhumanoid.info","http:\/\/pinterest.com\/super_humanoid","http:\/\/www.youtube.com\/SuperhumanoidInfo"]},{"@type":"Person","@id":"https:\/\/superhumanoid.info\/superblog\/#\/schema\/person\/26af13acaaa4eda46bfea79065a73fa3","name":"Pawel","image":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/www.superhumanoid.info\/superblog\/wp-content\/uploads\/Pawel_avatar_1404578456-96x96.jpg","url":"http:\/\/www.superhumanoid.info\/superblog\/wp-content\/uploads\/Pawel_avatar_1404578456-96x96.jpg","contentUrl":"http:\/\/www.superhumanoid.info\/superblog\/wp-content\/uploads\/Pawel_avatar_1404578456-96x96.jpg","caption":"Pawel"},"description":"Pawel M. Konefal (geb. 22.02.1981 in Oberschlesien) ist freier Autor und Blogger und auch ein stetiger Selbst-Verbesserer. Er hat 80 kg in 2 Jahren abgenommen und sein K\u00f6rpergewicht halbiert. Er wei\u00df wie es ist stark \u00fcbergewichtig zu sein und ist voller Begeisterung mit den Themen Evolution\u00e4rer Gesundheit, Ern\u00e4hrung, Bewegung, Gehirnfitness und effektiver Selbstverbesserung besch\u00e4ftigt. Au\u00dferdem liebt er Kochen mit einfachen, nat\u00fcrlichen und unverarbeiteten Nahrungsmitteln. Er betreibt gerne Sport in Form von HIIT (Hoch Intensive Interval Training), Freeletics und ist begeisterter Leser. Er ern\u00e4hrt sich gem\u00e4\u00df der Paleo-Di\u00e4t bzw. Pal\u00e4o-Ern\u00e4hrung oder auch Steinzeit-Di\u00e4t und unterst\u00fctzt eine gesunde Lebensweise. Er hat den Anspruch seine Erfahrungen zu nutzen um anderen zu helfen.","sameAs":["http:\/\/www.superhumanoid.info","https:\/\/www.facebook.com\/pawel.konefal","https:\/\/instagram.com\/superhumanoid.info\/","https:\/\/www.pinterest.com\/super_humanoid\/","https:\/\/x.com\/pawel_konefal","https:\/\/www.youtube.com\/user\/SuperhumanoidInfo"],"url":"https:\/\/superhumanoid.info\/superblog\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p4PQdV-UU","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/superhumanoid.info\/superblog\/wp-content\/uploads\/4-jahres-symposium-der-dgpe-01-10-2016-in-frankfurt-am-main.jpg?fit=1024%2C512&ssl=1","_links":{"self":[{"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/posts\/3528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/comments?post=3528"}],"version-history":[{"count":0,"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/posts\/3528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/media\/3529"}],"wp:attachment":[{"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/media?parent=3528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/categories?post=3528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/superhumanoid.info\/superblog\/wp-json\/wp\/v2\/tags?post=3528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}